{"id":757,"date":"2020-01-22T20:37:43","date_gmt":"2020-01-22T19:37:43","guid":{"rendered":"https:\/\/gruenspecht.at\/beitrag\/?p=757"},"modified":"2020-01-22T20:41:49","modified_gmt":"2020-01-22T19:41:49","slug":"umwelt012-rieder-bach","status":"publish","type":"post","link":"https:\/\/gruenspecht.at\/beitrag\/2020\/01\/22\/umwelt012-rieder-bach\/","title":{"rendered":"#umwelt012-rieder bach"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-758\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.jpg\" alt=\"Rieder bach\" width=\"850\" height=\"396\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach-300x140.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach-768x358.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<h3>Entlang des Rieder Baches von St\u00f6cklgras Richtung Aurolzm\u00fcnster wird derzeit eifrig gearbeitet. Im Bereich unter der Br\u00fccke Goethestra\u00dfe sind Sch\u00e4den bei der Steinschlichtung aufgetreten, die saniert werden m\u00fcssen. Teilweise wild entstandene Anlandungen links und rechts des schnurgeraden Bachlaufes wurden bei den Hub- und Erdarbeiten ebenso entdeckt wie eine durchg\u00e4ngige, halbkreisf\u00f6rmige Steinauskleidung. Nun wird von der Wehr oberhalb der Br\u00fccke entlang des Schulgartens der Waldm\u00fcllervolksschule durch das Entfernen der Ablagerungen dem Bach wieder mehr Raum gegeben, um eine M\u00e4andrierung zuzulassen.<\/h3>\n<p><!--more--><\/p>\n<figure id=\"attachment_759\" aria-describedby=\"caption-attachment-759\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-759\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.21.jpg\" alt=\"Umwelt012-Rieder Bach\" width=\"850\" height=\"449\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.21.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.21-300x158.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.21-768x406.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-759\" class=\"wp-caption-text\">Foto: Gr\u00fcnspecht &#8211; Rieder bach<\/figcaption><\/figure>\n<p>Im Zuge des Neubaus der Br\u00fccke in der Schillerstra\u00dfe soll dann der weitere Verlauf des Rieder Baches bis zur Einm\u00fcndung des Ottenbachs renaturiert werden.<\/p>\n<p>Au\u00dferdem werden am Radweg entlang des Baches Wildwuchs und Gestr\u00fcpp ausgelichtet, die Str\u00e4ucher erhalten einen Verj\u00fcngungsschnitt und auch B\u00e4ume, vorwiegend Eschen, werden gef\u00e4llt, sofern dies nach sorgf\u00e4ltiger Begutachtung erforderlich scheint. Das undurchdringliche Dickicht hat zu vermehrtem Auftreten von Ungeziefer, vor allem Ratten, gef\u00fchrt.<\/p>\n<p>Die mit dem Gew\u00e4sserbezirk akkordierten Pflegema\u00dfnahmen haben besorgte B\u00fcrger auf den Plan gerufen. Wird hier r\u00fccksichtslos gerodet? Leiden die Fische darunter, wenn sich das Wasser im Sommer durch die wegfallende Beschattung zu sehr erw\u00e4rmt? Was ist mit den br\u00fctenden V\u00f6geln?<\/p>\n<p>Nun: Es ist verboten, B\u00e4ume und Str\u00e4ucher w\u00e4hrend der Vogelbrutzeit vom 1. April bis 30. September zu f\u00e4llen. Es macht daher Sinn, die notwendigen Arbeiten jetzt durchzuf\u00fchren. Die Str\u00e4ucher treiben im Fr\u00fchjahr schnell wieder aus und bieten Lebensraum f\u00fcr V\u00f6gel und Insekten, auch eine gewisse Beschattung des Gew\u00e4ssers ist gegeben.<br \/>\nNachpflanzungen in diesem Bereich erfolgen in Absprache mit dem Gew\u00e4sserbezirk Braunau.<\/p>\n<figure id=\"attachment_760\" aria-describedby=\"caption-attachment-760\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-760\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.2.jpg\" alt=\"Rieder Bach\" width=\"850\" height=\"395\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.2.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.2-300x139.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2020\/01\/umwelt012-rieder-bach.2-768x357.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-760\" class=\"wp-caption-text\">Foto: Gr\u00fcnspecht &#8211; Rieder Bach<\/figcaption><\/figure>\n<p>\u00dcbrigens gibt es auch f\u00fcr Fische und andere Wasserbewohner in Teichen eine Schutzzeit. Das Ablassen von Wasser in Teichen ist w\u00e4hrend der Zeit vom 1. bis 31. Juli nicht gestattet.<\/p>\n<p>Bleibt die bedauerliche, aber notwendige F\u00e4llung der Eschen aufgrund des Eschentriebsterbens. Globalisierung und uneingeschr\u00e4nkte Mobilit\u00e4t haben es dem aus Amerika eingeschleppten todbringenden Pilz erm\u00f6glicht, seit ca. f\u00fcnf bis sechs Jahren die Eschen in unseren Breiten zu befallen, was zu einem massiven Absterben der B\u00e4ume gef\u00fchrt hat. Selbst wenn die Eschen im Fr\u00fchling noch austreiben und gesund wirken, kann es passieren, dass sie schon bei geringen Windgeschwindigkeiten pl\u00f6tzlich umfallen und eine Gefahr f\u00fcr Mensch und Tier darstellen.<\/p>\n<p>Grunds\u00e4tzlich ist anzumerken, dass das F\u00e4llen oder Schl\u00e4gern von einzelnen B\u00e4umen nicht bewilligungspflichtig ist, das Roden bzw. der Kahlschlag ganzer Waldfl\u00e4chen jedoch schon.<\/p>\n<p>\u201eWenn du up to date bleiben m\u00f6chtest, abonniere unseren\u00a0<a href=\"https:\/\/gruenspecht.at\/newsletter-anmeldung\/\">Newsletter<\/a>\u201e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entlang des Rieder Baches von St\u00f6cklgras Richtung Aurolzm\u00fcnster wird derzeit eifrig gearbeitet. Im Bereich unter der Br\u00fccke Goethestra\u00dfe sind Sch\u00e4den bei der Steinschlichtung aufgetreten, die saniert werden m\u00fcssen. Teilweise wild entstandene Anlandungen links und rechts des schnurgeraden Bachlaufes wurden bei den Hub- und Erdarbeiten ebenso entdeckt wie eine durchg\u00e4ngige, halbkreisf\u00f6rmige Steinauskleidung. Nun wird von der &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gruenspecht.at\/beitrag\/2020\/01\/22\/umwelt012-rieder-bach\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e#umwelt012-rieder bach\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[37],"tags":[43],"class_list":["post-757","post","type-post","status-publish","format-aside","hentry","category-wasser","tag-rieder-bach","post_format-post-format-aside"],"_links":{"self":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/comments?post=757"}],"version-history":[{"count":2,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/757\/revisions"}],"predecessor-version":[{"id":762,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/757\/revisions\/762"}],"wp:attachment":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/media?parent=757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/categories?post=757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/tags?post=757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}