{"id":684,"date":"2019-10-28T15:16:12","date_gmt":"2019-10-28T14:16:12","guid":{"rendered":"https:\/\/gruenspecht.at\/beitrag\/?p=684"},"modified":"2019-10-28T15:31:45","modified_gmt":"2019-10-28T14:31:45","slug":"verkehr016-spange3","status":"publish","type":"post","link":"https:\/\/gruenspecht.at\/beitrag\/2019\/10\/28\/verkehr016-spange3\/","title":{"rendered":"#verkehr016-spange3"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-686\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016.jpg\" alt=\"Verkehr-Spange 3\" width=\"850\" height=\"531\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016-300x187.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016-768x480.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/p>\n<h3>Der Rieder Gemeinderat hat in seiner Sitzung am 17. Oktober 2019 neuerlich die Verl\u00e4ngerung des Neuplanungsgebietes f\u00fcr die Spange 3 beschlossen. Dieses wurde erstmals 2005(!) verordnet.<\/p>\n<p>GR\u00dcNE, SP\u00d6 und NEOS stimmten dagegen.<\/p>\n<p>Im Zuge der Diskussion im Gemeinderat wurde von Stadtrat Mag. Lukas Oberwagner Stellung genommen. Ihm erschien vor allem die im Raum stehende Entlastung der Rieder Innenstadt im Umfang von ca. 5.500 Fahrzeugen als viel zu hoch gegriffen.<br \/>\nIm gesamten Planungsverlauf kam es nie zu einer seri\u00f6sen Verkehrsz\u00e4hlung: Die kolportierten Zahlen waren laut dem Sachverst\u00e4ndigen des Landes reine \u201cGlaskugel-Seherei\u201d. Diese Aussage des Sachverst\u00e4ndigen erfolgte \u00fcbrigens bei der Verhandlung \u00fcber den Bau der Spange 3.<\/h3>\n<p><!--more--><\/p>\n<figure id=\"attachment_689\" aria-describedby=\"caption-attachment-689\" style=\"width: 850px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-689\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016.1.jpg\" alt=\"Spange3 Ried im Innkreis\" width=\"850\" height=\"561\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016.1.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016.1-300x198.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2019\/10\/verkehr016.1-768x507.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-689\" class=\"wp-caption-text\">Foto: Gr\u00fcnspecht &#8211; Spange 3<\/figcaption><\/figure>\n<p>Wertvollste Gr\u00fcn- und Ackerfl\u00e4chen im Ausma\u00df von 40.000 Quadratmetern zu opfern und die dort vorhandene Biolandwirtschaft zu vernichten ist in Zeiten der Klimakatastrophe eine verantwortungslose Politik, die die Zukunft verr\u00e4t. Der damit verbundene Verlust unserer Ern\u00e4hrungssouver\u00e4nit\u00e4t und der B\u00f6den als wertvolle Wasserspeicher waren f\u00fcr die GR\u00dcNEN Grund genug, bei ihrer Ablehnung gegen\u00fcber diesem Projekt zu bleiben, wie auch schon die letzten Jahre.<\/p>\n<p>Der Gr\u00fcnspecht meint, dass die Stadt Ried nicht einerseits den Klimanotstand ausrufen und den Leerstand in der Innenstadt beklagen kann, und auf der anderen Seite Retropolitik betreibt. Nichts anderes ist es, wenn eine Stra\u00dfe gebaut werden soll, damit ein Betriebsansiedlungsgebiet erschlossen wird. Denn die Verkehrsentlastung durch die Spange 3 ist bislang durch nichts bewiesen. Das sagt zumindest der Sachverst\u00e4ndige des Landes.<\/p>\n<p>Der Schutz der wertvollen landwirtschaftlichen Produktionsfl\u00e4chen ist unabdingbares Gebot der Stunde. Tag f\u00fcr Tag sinkt durch die Verbauung der Selbstversorgungsgrad und \u00d6sterreich wird zunehmend von Importen abh\u00e4ngig und somit verletzbar. Gleichzeitig geht Tag f\u00fcr Tag durch die Verbauung der B\u00f6den wertvoller Wasserspeicher verloren und \u00dcberschwemmungssch\u00e4den nehmen zu.<br \/>\nEigentlich m\u00fcssten wir jedem Bauern, der noch weitermachen will, dreimal t\u00e4glich auf den Knien danken, statt ihn durch den Bau einer \u00fcberfl\u00fcssigen Stra\u00dfe zum Aufgeben zu zwingen.<\/p>\n<p>Angesichts der vielen jungen Menschen, die um ihre Zukunft k\u00e4mpfen: Wie k\u00f6nnen wir es wagen, sie nicht ernst zu nehmen und nicht alle Kr\u00e4fte gegen den Klimanotstand zu mobilisieren? Wie k\u00f6nnen wir es wagen, so weiter zu machen wie bisher und ihre Lebensgrundlage zerst\u00f6ren?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Rieder Gemeinderat hat in seiner Sitzung am 17. Oktober 2019 neuerlich die Verl\u00e4ngerung des Neuplanungsgebietes f\u00fcr die Spange 3 beschlossen. Dieses wurde erstmals 2005(!) verordnet. GR\u00dcNE, SP\u00d6 und NEOS stimmten dagegen. Im Zuge der Diskussion im Gemeinderat wurde von Stadtrat Mag. Lukas Oberwagner Stellung genommen. Ihm erschien vor allem die im Raum stehende Entlastung &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gruenspecht.at\/beitrag\/2019\/10\/28\/verkehr016-spange3\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e#verkehr016-spange3\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-684","post","type-post","status-publish","format-aside","hentry","category-individualverkehr","post_format-post-format-aside"],"_links":{"self":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/comments?post=684"}],"version-history":[{"count":11,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/684\/revisions"}],"predecessor-version":[{"id":697,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/684\/revisions\/697"}],"wp:attachment":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/media?parent=684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/categories?post=684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/tags?post=684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}