{"id":2609,"date":"2025-12-18T12:57:25","date_gmt":"2025-12-18T11:57:25","guid":{"rendered":"https:\/\/gruenspecht.at\/beitrag\/?p=2609"},"modified":"2025-12-20T22:02:27","modified_gmt":"2025-12-20T21:02:27","slug":"verkehr-011-bahnhof-ried-zugsicherungssysteme","status":"publish","type":"post","link":"https:\/\/gruenspecht.at\/beitrag\/2025\/12\/18\/verkehr-011-bahnhof-ried-zugsicherungssysteme\/","title":{"rendered":"#verkehr-011-bahnhof-ried-zugsicherungssysteme"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"531\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/stellwerk-1-zugsicherung.png\" alt=\"\" class=\"wp-image-2610\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/stellwerk-1-zugsicherung.png 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/stellwerk-1-zugsicherung-300x187.png 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/stellwerk-1-zugsicherung-768x480.png 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Vom Sicherheitspedal zur digitalen Leitstrecke: Die Entwicklung der Zugbeeinflussungssysteme<\/h2>\n\n\n\n<p>Die Eisenbahn geh\u00f6rt zu den sichersten Verkehrssystemen der Welt \u2013 und das nicht ohne Grund. Hinter jedem Zug steckt ein komplexes Netz technischer \u00dcberwachung, das sich \u00fcber Jahrzehnte stetig weiterentwickelt hat. Die Geschichte der Zugbeeinflussungssysteme in \u00d6sterreich zeigt eindrucksvoll, wie sich Sicherheitstechnik vom rein mechanischen Schutz hin zu einem hochdigitalen, europaweit harmonisierten System gewandelt hat.<\/p>\n\n\n\n<p><strong>Sifa: Sicherung durch Aufmerksamkeit<\/strong><br>Am Anfang stand ein vergleichsweise simples, aber wirkungsvolles Instrument: die Sicherheitsfahrschaltung, kurz Sifa. Sie wird unterschieden in Impuls-Sifa oder einfach Sifa. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Die &#8220;Impuls-Sifa&#8221; (Aufforderungs-Sifa) ist eine modernere Form der &#8220;einfachen&#8221; Zeit-Zeit-Sifa (Totmannschaltung). W\u00e4hrend die einfache Sifa den Lokf\u00fchrer zwingt, in festen Intervallen (z.B. alle 30s) meist ein Pedal\/Taster zu bet\u00e4tigen, fordert die Impuls-Sifa den Lokf\u00fchrer durch akustische und visuelle Signale auf, eine <em>aktive<\/em> Handlung auszuf\u00fchren (oft eine bestimmte Taste dr\u00fccken), was eine dynamischere \u00dcberwachung darstellt und auf neue Zugmodelle angepasst ist. Die Sifa sch\u00fctzt vor Sekundenschlaf und medizinischen Notf\u00e4llen \u2013 ein erster, grundlegender Baustein f\u00fcr den sicheren Bahnbetrieb.<\/p>\n\n\n\n<p><strong>Indusi und PZB: Magnetdaten als W\u00e4chter an der Strecke<\/strong><\/p>\n\n\n\n<p>Einen gro\u00dfen Schritt brachte die induktive Zugbeeinflussung (Indusi), sp\u00e4ter weiterentwickelt zur Punktf\u00f6rmigen Zugbeeinflussung (PZB). Sie beruht auf drei unterschiedlichen Gleismagneten:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"638\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/PZB1000.jpg\" alt=\"\" class=\"wp-image-2611\" style=\"aspect-ratio:1.3333333333333333;object-fit:contain;width:400px;height:auto\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/PZB1000.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/PZB1000-300x225.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/PZB1000-768x576.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption class=\"wp-element-caption\">Foto: Walter Oberwagner, Gleismagnet 1000Hz beim Vorsignal<\/figcaption><\/figure>\n<\/div>\n\n\n<p><strong>Gleismagnet 1000 Hz:<\/strong> Der wirksame GM 1000 Hz bewirkt am Fahrzeug, die Pr\u00fcfung der Geschwindigkeit innerhalb einer anschlie\u00dfenden oder nach Ablauf einer Pr\u00fcfzeit. Wird die Wachsamkeitstaste nicht innerhalb 4 Sekunden bet\u00e4tigt bzw. wird die Pr\u00fcfgeschwindigkeit \u00fcberschritten, so wird eine Zwangsbremsung ausgel\u00f6st. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>Gleismagnet 2000 Hz:<\/strong> Der wirksame GM 2000 Hz bewirkt eine Zwangsbremsung am Fahrzeug ohne Zeitverz\u00f6gerung.<\/p>\n\n\n\n<p><strong>Gleismagnet 500 Hz:<\/strong> Der wirksame 500 Hz bewirkt am Fahrzeug die \u00dcberpr\u00fcfung einer Geschwindigkeit. Beim \u00dcberschreiten dieser fahrzeugseitig vorgegebenen Pr\u00fcfgeschwindigkeit erfolgt eine Zwangsbremsung ohne Zeitverz\u00f6gerung<\/p>\n\n\n\n<p>\u00dcberf\u00e4hrt der Fahrzeugmagnet einen wirksamen (\u201escharfen\u201c) GM, l\u00f6st dies je nach Betriebsprogramm ein entsprechendes \u00dcberwachungsprogramm aus, bzw. f\u00fchrt unmittelbar zu einer Zwangsbremsung.<\/p>\n\n\n\n<p>Noch heute ist sie das R\u00fcckgrat der Sicherheit auf weiten Teilen des \u00d6BB Netzes.<\/p>\n\n\n\n<p><br><strong>Linienzugbeeinflussung<\/strong> (<strong>LZB) Grundprinzip<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"366\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/LZB.png\" alt=\"\" class=\"wp-image-2629\" style=\"width:400px;height:auto\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/LZB.png 400w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/LZB-300x275.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n<\/div>\n\n\n<p>Mit dem Aufkommen der Schnellfahrstrecken reichten punktuelle Informationen nicht mehr aus. Die Linienzugbeeinflussung (LZB) bietet deshalb eine kontinuierliche und weit vorausschauende \u00dcberwachung. Im Gegensatz zu PZB und Indusi wird bei LZB nicht punktf\u00f6rmig, sondern kontinuierlich \u00fcberwacht. Das Herzst\u00fcck der LZB sind zwei parallel im Gleis verlegte Linienleiterkabel, in denen codierte elektrische Signale laufen. Diese Kabel bilden einen durchgehenden Informationskanal zwischen Zug und Streckenzentrale. Der Zug sendet und empf\u00e4ngt Daten \u00fcber induktive Koppler  ohne physischen Kontakt zum Gleis.<\/p>\n\n\n\n<p>In der LZB sind drei Geschwindigkeiten ma\u00dfgebend, wobei jeweils die niedrigste dem Triebfahrzeugf\u00fchrer angezeigt wird<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>zul\u00e4ssige Geschwindigkeit<\/li>\n\n\n\n<li>Einschr\u00e4nkungen der Geschwindigkeit<\/li>\n\n\n\n<li>Die Geschwindigkeit die durch den Zug begr\u00fcndet ist<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<p><strong>ETCS: Europas einheitlicher Standard<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"533\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/Siemens-balise.png\" alt=\"\" class=\"wp-image-2632\" style=\"width:400px\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/Siemens-balise.png 400w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/Siemens-balise-225x300.png 225w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><figcaption class=\"wp-element-caption\">Ein Ausfahrsignal mit einem 2000 Hz-Magneten und 2 ETCS-Balisen. Bei haltzeigendem Signal ist der Gleismagnet &#8220;scharf&#8221;. Es wird sofort eine Zwangsbremsung ausgel\u00f6st.<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Das European Train Control System (ETCS) ersetzt nach und nach nationale Systeme, um den grenz\u00fcberschreitenden Bahnbetrieb zu vereinheitlichen.<\/p>\n\n\n\n<p><strong>ETCS Level 1<\/strong> nutzt Eurobalisen zur punktuellen Informations\u00fcbertragung \u2013 \u00e4hnlich der PZB, aber moderner und international standardisiert.<\/p>\n\n\n\n<p><strong>ETCS Level 2<\/strong> \u00fcbermittelt Fahrdaten kontinuierlich per Zugfunk. Optische Signale an der Strecke werden weitgehend \u00fcberfl\u00fcssig; der F\u00fchrerstand erh\u00e4lt s\u00e4mtliche Informationen digital. <\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>In folgender Grafik ist der Ausbauzustand von PZB \u00fcber LZB zu ETCS Level 1 und Level 2 dargestellt<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"430\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/Sicherungskarte.png\" alt=\"\" class=\"wp-image-2614\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/Sicherungskarte.png 735w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2025\/12\/Sicherungskarte-300x176.png 300w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><figcaption class=\"wp-element-caption\"><a href=\"https:\/\/infrastruktur.oebb.at\/de\/geschaeftspartner\/schienennetz\/dokumente-und-daten\/etcs-zugbeeinflussung\/etcs-ausbau\/etcs-liste\">https:\/\/infrastruktur.oebb.at\/de\/geschaeftspartner\/schienennetz\/dokumente-und-daten\/etcs-zugbeeinflussung\/etcs-ausbau\/etcs-liste<\/a><\/figcaption><\/figure>\n\n\n\n<p>Ried &#8211; Wien Streckenausr\u00fcstung Mitte des Jahres 2025<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Ried im Inkreis<\/td><td>Neumarkt-Kallham<\/td><td>PZB<\/td><\/tr><tr><td>Neumarkt-Kallham<\/td><td>Haiding<\/td><td>ETCS Level 1<\/td><\/tr><tr><td>Haiding<\/td><td>Linz Hbf<\/td><td>ETCS Level 2<\/td><\/tr><tr><td>Linz Hbf \/ Neubaustrecke<\/td><td>St. P\u00f6lten<\/td><td>LZB<\/td><\/tr><tr><td>St. P\u00f6lten \/ Neubaustrecke<\/td><td>Wien \u00fcber Tullnerfeld<\/td><td>ETCS Level 2<\/td><\/tr><tr><td><\/td><td><\/td><td><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p><strong>ETCS Level 3:<\/strong> Die Zukunft der signalfreien Bahn! Damit steht die n\u00e4chste Generation in den Startl\u00f6chern. Das System basiert auf beweglichen Blockabschnitten, bei denen der Zug seine Position selbst bestimmt und meldet \u2013 ohne feste Streckenbl\u00f6cke. Damit k\u00f6nnten Z\u00fcge dichter aufeinander fahren und die Kapazit\u00e4t stark steigen, ohne dass zus\u00e4tzliche Infrastruktur n\u00f6tig w\u00e4re. Erste Tests laufen bereits.<\/p>\n\n\n\n<p><strong>Fazit: <\/strong>Vom einfachen Sicherheitsfahrschalter \u00fcber die Indusi-Magnete, LZB bis hin zu hochdigitalen ETCS-Stufen: Die Entwicklung der Zugbeeinflussungssysteme zeigt den Weg einer Bahn, die immer sicherer, leistungsf\u00e4higer und vernetzter wird \u2013 und bereit ist f\u00fcr den europ\u00e4ischen Hochgeschwindigkeitsverkehr der Zukunft.<\/p>\n\n\n\n<p><strong>Quellenverzeichnis<\/strong><\/p>\n\n\n\n<ul start=\"1\" class=\"wp-block-list\">\n<li><strong>\u00d6BB-Infrastruktur AG<\/strong><br><em>Zugsicherung und Zugbeeinflussung bei den \u00d6BB.<\/em><br>Interne Schulungsunterlagen und technische Systembeschreibungen, Wien.<\/li>\n<\/ul>\n\n\n\n<p><em>Richtlinien zur Punktf\u00f6rmigen Zugbeeinflussung (PZB) und Linienzugbeeinflussung (LZB).<\/em><br>\u00d6BB <em>Betriebsvorschriften <\/em><\/p>\n\n\n\n<ul start=\"2\" class=\"wp-block-list\">\n<li><strong>European Union Agency for Railways (ERA)<\/strong><br><em>ETCS \u2013 European Train Control System: System Description.<\/em><br>ERA Technical Documentation, Valenciennes.<\/li>\n\n\n\n<li><strong>UIC \u2013 Internationaler Eisenbahnverband<\/strong><br><em>ERTMS\/ETCS \u2013 Grundlagen und Anwendung im europ\u00e4ischen Eisenbahnverkehr.<\/em><br>Paris.<\/li>\n\n\n\n<li><strong>Wikipedia<\/strong>\n<ul class=\"wp-block-list\">\n<li>\u201eSicherheitsfahrschaltung (Sifa)\u201c<\/li>\n\n\n\n<li>\u201eInduktive Zugsicherung \/ Punktf\u00f6rmige Zugbeeinflussung (PZB)\u201c<\/li>\n\n\n\n<li>\u201eLinienzugbeeinflussung (LZB)\u201c<\/li>\n\n\n\n<li>\u201eEuropean Train Control System (ETCS)\u201c<br>https:\/\/de.wikipedia.org<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Siemens Mobility<\/strong><br><em>ETCS Level 1, Level 2 und Level 3 \u2013 System\u00fcbersicht und Entwicklung.<\/em><br>Produkt- und Systeminformationen.<\/li>\n\n\n\n<li><strong>Alstom Transport<\/strong><br><em>ERTMS\/ETCS Signalling Solutions \u2013 Technical Overview.<\/em><\/li>\n\n\n\n<li><strong>Fachliteratur<\/strong><br>Pachl, J.: <em>Systemtechnik des Schienenverkehrs \u2013 Bahnbetrieb planen, steuern und sichern.<\/em><br>Springer Vieweg, Wiesbaden.<\/li>\n<\/ul>\n\n\n\n<p>Zum Artikel Stellwerkstechnik  &gt;&gt;&gt;   <a href=\"https:\/\/gruenspecht.at\/beitrag\/2025\/12\/10\/verkehr-011-bahnhof-ried\/\">https:\/\/gruenspecht.at\/beitrag\/2025\/12\/10\/verkehr-011-bahnhof-ried\/<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p>\u201eWenn du up to date bleiben m\u00f6chtest, abonniere unseren&nbsp;<a href=\"https:\/\/gruenspecht.at\/newsletter-anmeldung\/\">Newsletter<\/a>\u201e<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vom Sicherheitspedal zur digitalen Leitstrecke: Die Entwicklung der Zugbeeinflussungssysteme Die Eisenbahn geh\u00f6rt zu den sichersten Verkehrssystemen der Welt \u2013 und das nicht ohne Grund. Hinter jedem Zug steckt ein komplexes Netz technischer \u00dcberwachung, das sich \u00fcber Jahrzehnte stetig weiterentwickelt hat. Die Geschichte der Zugbeeinflussungssysteme in \u00d6sterreich zeigt eindrucksvoll, wie sich Sicherheitstechnik vom rein mechanischen Schutz &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gruenspecht.at\/beitrag\/2025\/12\/18\/verkehr-011-bahnhof-ried-zugsicherungssysteme\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e#verkehr-011-bahnhof-ried-zugsicherungssysteme\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[13,10],"tags":[],"class_list":["post-2609","post","type-post","status-publish","format-aside","hentry","category-oeffentlicher-verkehr","category-verkehr","post_format-post-format-aside"],"_links":{"self":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/2609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/comments?post=2609"}],"version-history":[{"count":10,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/2609\/revisions"}],"predecessor-version":[{"id":2635,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/2609\/revisions\/2635"}],"wp:attachment":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/media?parent=2609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/categories?post=2609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/tags?post=2609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}