{"id":1666,"date":"2023-02-12T17:01:17","date_gmt":"2023-02-12T16:01:17","guid":{"rendered":"https:\/\/gruenspecht.at\/beitrag\/?p=1666"},"modified":"2024-01-02T09:33:41","modified_gmt":"2024-01-02T08:33:41","slug":"wirtschaft017-energie-ried-wo-ist-die-museumsspende","status":"publish","type":"post","link":"https:\/\/gruenspecht.at\/beitrag\/2023\/02\/12\/wirtschaft017-energie-ried-wo-ist-die-museumsspende\/","title":{"rendered":"#wirtschaft017-energie-ried-wo-ist-die-museumsspende"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"433\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-wo-ist-die-museumsspende-gelb.jpg\" alt=\"\" class=\"wp-image-1667\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-wo-ist-die-museumsspende-gelb.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-wo-ist-die-museumsspende-gelb-300x153.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-wo-ist-die-museumsspende-gelb-768x391.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Wirbel um Nazi-Ausstellung im Volkskundehaus: Energie Ried lie\u00df der Stadt Ende des Jahres blitzartig 350.000 Euro zukommen<\/h2>\n\n\n\n<p>Dieser Tage sorgte Ried wieder einmal f\u00fcr landesweite Schlagzeilen, leider im negativen Sinne. Die Ober\u00f6sterreichischen Nachrichten (O\u00d6N) emp\u00f6rten sich in zwei gro\u00dfformatigen Geschichten, siehe u.a. \u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/www.nachrichten.at\/kultur\/wie-stellt-man-die-kunst-eines-nazis-aus-so-nicht;art16,3785457\" target=\"_blank\">https:\/\/www.nachrichten.at\/kultur\/wie-stellt-man-die-kunst-eines-nazis-aus-so-nicht;art16,3785457<\/a>\u00a0dar\u00fcber, dass im Volkskundehaus eine unkritische Ausstellung des <em>\u201egl\u00fchenden Nationalsozialisten&#8221;<\/em> Ernst August von Mandelsloh (1886 \u2013 1962) er\u00f6ffnet wurde. W\u00f6rtlich hie\u00df es : <em>\u201eAuf drei Ebenen werden Zeichnungen und Aquarelle dieses unbedeutenden K\u00fcnstlers und Nazi-Schergen ohne Einordnung gezeigt&#8221;<\/em>. Mehr noch: <em>\u201eIm Begleittext zur Ausstellung wurde Mandelslohs Politkarriere gar als \u201abeeindruckend&#8217; bezeichnet&#8221;<\/em>, notierten die \u00d6ON. und zitierten B\u00fcrgermeister Bernhard Zwielehner  (\u00d6VP) in der Ausgabe vom 7. Februar mit folgenden Worten: <em>\u201eIch bin kein Historiker und will nicht beurteilen, ob das Thema mit dieser Ausstellung gut oder schlecht aufgearbeitet wurde.&#8221;<\/em><\/p>\n\n\n\n<!--more-->\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"515\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-volkskundehaus.jpg\" alt=\"Wo ist die Museumsspende\" class=\"wp-image-1678\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-volkskundehaus.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-volkskundehaus-300x182.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/wirtschaft017-volkskundehaus-768x465.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption class=\"wp-element-caption\">Foto: Gr\u00fcnspecht<\/figcaption><\/figure>\n\n\n\n<p>Nun ist der Gr\u00fcnspecht kein B\u00fcrgermeister, doch fragt er sich, wohin die in den O\u00d6N genannten 350.000 Euro der Energie Ried gegangen sind, die Zwielehner in den letzten Tagen des Jahres 2022 als Chef der Generalversammlung als sogenannte <em>\u201eMuseumsspende<\/em>&#8221; anweisen lie\u00df. An das <em>\u201eMuseum Innviertler Volkskundehaus&#8221;<\/em> offensichtlich noch nicht. Denn die Volkskundehaus-Chefin erkl\u00e4rte in den Ober\u00f6sterreichischen Nachrichten als Mitgrund f\u00fcr den Nazi-Fauxpas: <em>\u201eVon der Stadtgemeinde Ried wurde mir das Budget gek\u00fcrzt, Mitarbeiterinnen sind erkrankt, das alles hat mich in die Bredouille gebracht.&#8221;\u00a0<\/em><\/p>\n\n\n\n<p>Wohin verirrte sich die 350.000-Euro-Museumsspende der Energie Ried, die mit dem Firmen-Logo sogar auf der Einladung zur Nazi-Schau pr\u00e4sent war, wenn das Volkskundehaus \u00fcber fehlende Ressourcen klagt? Der Gr\u00fcnspecht wird nachbohren. In alle Richtungen.&nbsp;Auch wenn die Ausstellung am 8. Februar mit sofortiger Wirkung geschlossen wurde.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p>\u201eWenn du up to date bleiben m\u00f6chtest, abonniere unseren&nbsp;<a href=\"https:\/\/gruenspecht.at\/newsletter-anmeldung\/\">Newsletter<\/a>\u201e<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Wirbel um Nazi-Ausstellung im Volkskundehaus: Energie Ried lie\u00df der Stadt Ende des Jahres blitzartig 350.000 Euro zukommen Dieser Tage sorgte Ried wieder einmal f\u00fcr landesweite Schlagzeilen, leider im negativen Sinne. Die Ober\u00f6sterreichischen Nachrichten (O\u00d6N) emp\u00f6rten sich in zwei gro\u00dfformatigen Geschichten, siehe u.a. \u00a0https:\/\/www.nachrichten.at\/kultur\/wie-stellt-man-die-kunst-eines-nazis-aus-so-nicht;art16,3785457\u00a0dar\u00fcber, dass im Volkskundehaus eine unkritische Ausstellung des \u201egl\u00fchenden Nationalsozialisten&#8221; Ernst August von &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gruenspecht.at\/beitrag\/2023\/02\/12\/wirtschaft017-energie-ried-wo-ist-die-museumsspende\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e#wirtschaft017-energie-ried-wo-ist-die-museumsspende\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[78],"tags":[],"class_list":["post-1666","post","type-post","status-publish","format-aside","hentry","category-energie-ried","post_format-post-format-aside"],"_links":{"self":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/comments?post=1666"}],"version-history":[{"count":8,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1666\/revisions"}],"predecessor-version":[{"id":1681,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1666\/revisions\/1681"}],"wp:attachment":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/media?parent=1666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/categories?post=1666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/tags?post=1666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}