{"id":1661,"date":"2023-02-09T20:34:42","date_gmt":"2023-02-09T19:34:42","guid":{"rendered":"https:\/\/gruenspecht.at\/beitrag\/?p=1661"},"modified":"2023-02-09T20:42:16","modified_gmt":"2023-02-09T19:42:16","slug":"umwelt035-bienen","status":"publish","type":"post","link":"https:\/\/gruenspecht.at\/beitrag\/2023\/02\/09\/umwelt035-bienen\/","title":{"rendered":"#umwelt035-bienen"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"460\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/Bienen-2023-1.jpg\" alt=\"Bienenfreundliche Gemeinde\" class=\"wp-image-1662\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/Bienen-2023-1.jpg 860w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/Bienen-2023-1-300x160.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/02\/Bienen-2023-1-768x411.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Am <strong>Donnerstag, den 16.02.2023<\/strong> um <strong>17:30 Uhr<\/strong> findet der Startworkshop des Projektes <strong>\u201eBienenfreundliche Gemeinde\u201c<\/strong> statt. <\/h2>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\"> <strong>Stadtentwicklungsforum, Rossmarkt 33, Ried im Innkrei<\/strong><\/mark><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">s<\/mark><\/strong><\/h2>\n\n\n\n<!--more-->\n\n\n\n<p>Nach einem Input durch das Bodenb\u00fcndnis O\u00d6 werden wir zu den Handlungsfeldern Bienenfreundlicher \u00f6ffentlicher Raum, Bienenfreundlich Garteln und Bewusstseinsbildung, Bienenfreundliche Betriebe sowie Bienenfreundliche Landwirtschaft Projektideen entwickeln \u2013 im Projekt verpflichtend ist der Verzicht auf chemisch-synthetische Pflanzenschutzmittel auf \u00f6ffentlichen Fl\u00e4chen. Wir w\u00fcrden uns sehr \u00fcber Ihre Teilnahme und Ihre Ideen f\u00fcr <strong>Ried im Innkreis<\/strong> freuen.<\/p>\n\n\n\n<p>Weitere Schritte im Projekt werden sein: eine Begehung \u00f6ffentlicher Fl\u00e4chen mit Fachexperten sowie ein Umsetzungsworkshop zur Konkretisierung von Ma\u00dfnahmen.<\/p>\n\n\n\n<p>Das Projekt \u201eBienenfreundliche Gemeinde\u201c soll uns die n\u00e4chsten Jahre bei unseren Bem\u00fchungen begleiten. Unter dem Motto \u201eUnser Boden f\u00fcr Bienen\u201c soll mehr Vielfalt in unserer Gemeinde erbl\u00fchen und ein Beitrag zum Schutz der (Wild)Bienen und unseres Bodens geleistet werden.<\/p>\n\n\n\n<p>Auf Ihre Teilnahme am Workshop freut sich, <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">der Ausschuss f\u00fcr Umwelt, \u00f6ffentliche Erholungsgebiete und Tierschutz<\/mark><\/strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">,<\/mark> <strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">sowie die Vertreter der Stadtgemeinde Ried im Innkreis<\/mark><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p>\u201eWenn du up to date bleiben m\u00f6chtest, abonniere unseren\u00a0<a href=\"https:\/\/gruenspecht.at\/newsletter-anmeldung\/\">Newsletter<\/a>\u201e<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Am Donnerstag, den 16.02.2023 um 17:30 Uhr findet der Startworkshop des Projektes \u201eBienenfreundliche Gemeinde\u201c statt. Stadtentwicklungsforum, Rossmarkt 33, Ried im Innkreis<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[36,18],"tags":[],"class_list":["post-1661","post","type-post","status-publish","format-aside","hentry","category-tierschutz","category-umwelt","post_format-post-format-aside"],"_links":{"self":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/comments?post=1661"}],"version-history":[{"count":3,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1661\/revisions"}],"predecessor-version":[{"id":1665,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1661\/revisions\/1665"}],"wp:attachment":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/media?parent=1661"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/categories?post=1661"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/tags?post=1661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}