{"id":1572,"date":"2023-01-13T19:01:15","date_gmt":"2023-01-13T18:01:15","guid":{"rendered":"https:\/\/gruenspecht.at\/beitrag\/?p=1572"},"modified":"2023-01-15T13:39:50","modified_gmt":"2023-01-15T12:39:50","slug":"umwelt032-stadtpark","status":"publish","type":"post","link":"https:\/\/gruenspecht.at\/beitrag\/2023\/01\/13\/umwelt032-stadtpark\/","title":{"rendered":"#umwelt032-stadtpark"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"563\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/01\/schwarzbau-im-stadtpark1-1.jpg\" alt=\"Fakten zum &quot;Schwarzbau&quot;\" class=\"wp-image-1609\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/01\/schwarzbau-im-stadtpark1-1.jpg 850w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/01\/schwarzbau-im-stadtpark1-1-300x199.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2023\/01\/schwarzbau-im-stadtpark1-1-768x509.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Der ehemalige B\u00fcrgermeister Albert Ortig hat innerhalb seiner Kompetenz das Aufstellen von Holzpfl\u00f6cken angeordnet, um das<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>r\u00fccksichtslose Parken von Autos entlang des gesamten Sch\u00f6nauerwegs, trotz der beengten Stra\u00dfenverh\u00e4ltnisse, und das<\/li><li>unzul\u00e4ssige Parken in Gr\u00fcnfl\u00e4chen und von PKWs niedergem\u00e4hte Blumen und Str\u00e4ucher<\/li><\/ul>\n\n\n\n<p>zu verhindern.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Die Montage der urspr\u00fcnglichen Pfosten durch den St\u00e4dt. Wirtschaftshof hat rund 5.000 Euro gekostet, was den Rahmen der dem B\u00fcrgermeister frei zur Verf\u00fcgung stehenden Mittel von rund 14.000 Euro NICHT \u00fcberschritt.<\/p>\n\n\n\n<p>Link: <a href=\"https:\/\/gruenspecht.at\/beitrag\/2022\/07\/08\/umwelt029-stadtpark\/\">#umwelt029-stadtpark<\/a>, <a href=\"https:\/\/www.nachrichten.at\/oberoesterreich\/innviertel\/schwarzbau-holzpflockgalerie-war-sie-illegal;art70,3772753?fbclid=IwAR2kaxXXKlENv5zNy7pUbECib4TWUPEDhLgCvv-W7Oc89diYYOqBrqI67po\">O\u00d6 Nachrichten Plus<\/a><\/p>\n\n\n\n<p><strong>In der Stadtratssitzung vom 04.03.2021 wurde einstimmig &#8211; auch mit der Stimme des im Artikel angef\u00fchrten Vizeb\u00fcrgermeisters &#8211; die Anbringung eines Handlaufes bei den sp\u00e4ter nach und nach erweiterten Pfosten beschlossen.<\/strong> Erst dadurch kam es zu Gesamtkosten von \u00fcber 19.000 Euro. Die \u00dcberschreitung des Rahmens um 5.000 Euro war also durch das zust\u00e4ndige Gremium abgesegnet!<\/p>\n\n\n\n<p>In dem Artikel wird, nach Ansicht des Gr\u00fcnspechts, der Leserschaft suggeriert, dass es hier zu einer Missachtung von gemeinderelevanten Gesetzen gekommen ist.  <\/p>\n\n\n\n<p>Weder ist die Behauptung richtig, dass der Gemeinderat die Errichtung der Pfosten beschlie\u00dfen h\u00e4tte m\u00fcssen, noch dass es sich um einen \u201eillegalen Schwarzbau\u201c handelt. Das Aufstellen besagter Pfosten stellte <strong>keine baubewilligungspflichtige Ma\u00dfnahme<\/strong> dar!<\/p>\n\n\n\n<p>In der Gemeinderatssitzung am 7.  Juni  2022 wurde mit Mehrheitsbeschluss das Entfernen des Holzgel\u00e4nders und das Auflassen des Halte- und Parkverbots in Teilbereichen des Sch\u00f6nauerweges beschlossen. Zum Schaden der Verkehrssicherheit und zum Schaden der Gr\u00fcnanlagen.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p>\u201eWenn du up to date bleiben m\u00f6chtest, abonniere unseren&nbsp;<a href=\"https:\/\/gruenspecht.at\/newsletter-anmeldung\/\">Newsletter<\/a>\u201e<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Der ehemalige B\u00fcrgermeister Albert Ortig hat innerhalb seiner Kompetenz das Aufstellen von Holzpfl\u00f6cken angeordnet, um das r\u00fccksichtslose Parken von Autos entlang des gesamten Sch\u00f6nauerwegs, trotz der beengten Stra\u00dfenverh\u00e4ltnisse, und das unzul\u00e4ssige Parken in Gr\u00fcnfl\u00e4chen und von PKWs niedergem\u00e4hte Blumen und Str\u00e4ucher zu verhindern.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-1572","post","type-post","status-publish","format-aside","hentry","category-umwelt","post_format-post-format-aside"],"_links":{"self":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/comments?post=1572"}],"version-history":[{"count":23,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1572\/revisions"}],"predecessor-version":[{"id":1618,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1572\/revisions\/1618"}],"wp:attachment":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/media?parent=1572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/categories?post=1572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/tags?post=1572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}