{"id":1263,"date":"2022-03-28T20:06:12","date_gmt":"2022-03-28T18:06:12","guid":{"rendered":"https:\/\/gruenspecht.at\/beitrag\/?p=1263"},"modified":"2022-03-29T11:08:28","modified_gmt":"2022-03-29T09:08:28","slug":"umwelt025","status":"publish","type":"post","link":"https:\/\/gruenspecht.at\/beitrag\/2022\/03\/28\/umwelt025\/","title":{"rendered":"#umwelt025"},"content":{"rendered":"<figure id=\"attachment_1264\" aria-describedby=\"caption-attachment-1264\" style=\"width: 840px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1264\" src=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2022\/03\/umwelt025-foto.jpg\" alt=\"Seit Wochen kein Tropfen Wasser\" width=\"840\" height=\"470\" srcset=\"https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2022\/03\/umwelt025-foto.jpg 840w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2022\/03\/umwelt025-foto-300x168.jpg 300w, https:\/\/gruenspecht.at\/beitrag\/wp-content\/uploads\/sites\/3\/2022\/03\/umwelt025-foto-768x430.jpg 768w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><figcaption id=\"caption-attachment-1264\" class=\"wp-caption-text\">Foto: Gr\u00fcnspecht<\/figcaption><\/figure>\n<h2>Seit Wochen kein Tropfen Wasser<\/h2>\n<p>Wenn man mit dem Fahrrad \u00fcbers Land f\u00e4hrt, ist fest zustellen, dass es gewaltig staubt, wenn der Bauer seine Wiesen und Felder eggt. Regen in ausreichender Menge ist in n\u00e4chster Zeit nicht angek\u00fcndigt. Dass die langen stabilen Hochwetterphasen zunehmen, war bereits in den vergangenen Jahren zu bemerken. Trotzdem ist es heuer extrem.<!--more--><\/p>\n<p>Mitten in Europa &#8211; in der Ukraine &#8211; w\u00fctet ein brutaler Krieg, es droht eine massive Energie- und Ern\u00e4hrungskrise. Allen ist klar: Wir werden k\u00fcnftig jeden Quadratmeter Boden, jeden Landwirt brauchen, um diese Krise und die kommenden klimapolitischen Herausforderungen zu bew\u00e4ltigen.<\/p>\n<p>Sp\u00fcrbar ist die Erderw\u00e4rmung aber auch an den zunehmenden Wetterextremen, die die Landwirtschaft unmittelbar treffen. Allein im ersten Halbjahr 2021 gab es Sch\u00e4den im Ausma\u00df von 220 Millionen Euro, in den letzten 5 Jahren eine Milliarde Gesamtschaden in der Landwirtschaft!<\/p>\n<p style=\"text-align: center;\"><strong>\u201eKein zweites Land geht so sorglos mit seinen B\u00f6den um\u201c<\/strong><br \/>\n<code>(Kurt Weinberger Chef der \u00f6sterrr. Hagelversicherung in den O\u00f6.Nachrichten vom 26.3.2022)<\/code><\/p>\n<p>Der Klimawandel macht nicht vor \u00d6sterreich Halt, daher ist auch hier die Erf\u00fcllung v\u00f6lkerrechtlicher Verpflichtungen &#8211; wie der Vertrag von Paris &#8211; eine Grundvoraussetzung, um den Planet Erde f\u00fcr deren Bewohner zu retten. Hauptproblem in \u00d6sterreich ist die z\u00f6gerliche Reduzierung der CO2 -Emissionen des Verkehrs, die zwischen 1990 und 2020 um 49,4% gestiegen sind.<\/p>\n<p>Der Chef der \u00f6sterr. Hagelversicherung sowie die Vorstandsdirektorin der als weltweit f\u00fchrend geltenden M\u00fcnchener R\u00fcck weisen in einer Pressekonferenz auf die Notwendigkeit von:<\/p>\n<p>&#8211; eine Attraktivierung von klimafreundlichen Handeln gegen\u00fcber einem klimasch\u00e4dlichen<br \/>\n&#8211; Ausbau erneuerbarer Energietr\u00e4ger und rasche Umsetzung einer \u00f6kosozialen Steuerreform<br \/>\n&#8211; <span style=\"background-color: yellow;\">Verkehrsprobleme sind nicht durch neue Stra\u00dfen zu l\u00f6sen \u2013 es gilt die Symptome zu bek\u00e4mpfen. So werden beispielsweise Kartoffeln von Holland zum Sch\u00e4len nach Marokko transportiert<\/span><br \/>\n&#8211; Dem Bodenverbrauch muss Einhalt geboten werden. In den vergangenen 25 Jahren wurden 150.000 Hektar \u00c4cker und Wiesendurch Verbauung der Landwirtschaft entzogen. Diese Fl\u00e4che entspricht der gesamten Ackerfl\u00e4che des Burgenlandes<br \/>\n&#8211; Revitalisierungsoffensive der mehr als 40.00 Hektar leerstehenden Immobilien<br \/>\n&#8211; Chancen nutzen, die im \u201eGreen Deal\u201c stecken \u2013 nachhaltige regional Wirtschaft, die Arbeitspl\u00e4tze sichert bzw. schafft und die Umwelt zum Wohle der nachkommenden Generationen schont.<\/p>\n<p>Ouellen:<br \/>\nAPA Aussendung (OTS)- (\u00d6sterreichische Hagelversicherung , 26. August\u00a0 2021) Pressetext &gt;&gt; <a href=\"https:\/\/gruenspecht.at\/pdf-downloads\/Umwelt\/Hagelversicherung-Klimakrise-Ist-es-nicht-schon-zu-spaet.pdf\">Hagelversicherung: Klimakrise &#8211; Ist es nicht schon zu sp\u00e4t? &#8211; 1,8MB<\/a><br \/>\nO\u00d6 Nachrichten<br \/>\nDer Standard<br \/>\nSWR Wissen<\/p>\n<p>Links: \u00a0 &#8211;\u00a0<a href=\"https:\/\/gruenspecht.at\/beitrag\/2019\/03\/28\/umwelt004-resolution-fuer-den-schutz-von-boeden-und-artenvielfalt\/#more-544\">https:\/\/gruenspecht.at\/beitrag\/2019\/03\/28\/umwelt004-resolution-fuer-den-schutz-von-boeden-und-artenvielfalt\/#more-544<\/a><br \/>\n<a href=\"https:\/\/gruenspecht.at\/beitrag\/2018\/09\/23\/klimaschutz001-bodenbuendnis\">\u00a0&#8211; https:\/\/gruenspecht.at\/beitrag\/2018\/09\/23\/klimaschutz001-bodenbuendnis<\/a><\/p>\n<hr \/>\n<p>\u201eWenn du up to date bleiben m\u00f6chtest, abonniere unseren\u00a0<a href=\"https:\/\/gruenspecht.at\/newsletter-anmeldung\/\">Newsletter<\/a>\u201e<\/p>\n<hr \/>\n","protected":false},"excerpt":{"rendered":"<p>Seit Wochen kein Tropfen Wasser Wenn man mit dem Fahrrad \u00fcbers Land f\u00e4hrt, ist fest zustellen, dass es gewaltig staubt, wenn der Bauer seine Wiesen und Felder eggt. Regen in ausreichender Menge ist in n\u00e4chster Zeit nicht angek\u00fcndigt. Dass die langen stabilen Hochwetterphasen zunehmen, war bereits in den vergangenen Jahren zu bemerken. Trotzdem ist es &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/gruenspecht.at\/beitrag\/2022\/03\/28\/umwelt025\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e#umwelt025\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"aside","meta":{"footnotes":""},"categories":[25,18],"tags":[],"class_list":["post-1263","post","type-post","status-publish","format-aside","hentry","category-klimaschutz-naherholung","category-umwelt","post_format-post-format-aside"],"_links":{"self":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/comments?post=1263"}],"version-history":[{"count":7,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1263\/revisions"}],"predecessor-version":[{"id":1283,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/posts\/1263\/revisions\/1283"}],"wp:attachment":[{"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/media?parent=1263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/categories?post=1263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruenspecht.at\/beitrag\/wp-json\/wp\/v2\/tags?post=1263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}